{"id":151,"count":1,"description":"","link":"https:\/\/katiepfeiffer.com\/blog\/category\/fashion\/","name":"fashion","slug":"fashion","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/katiepfeiffer.com\/blog\/wp-json\/wp\/v2\/categories\/151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/katiepfeiffer.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/katiepfeiffer.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/katiepfeiffer.com\/blog\/wp-json\/wp\/v2\/posts?categories=151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}