{"id":647,"count":1,"description":"","link":"https:\/\/katiepfeiffer.com\/blog\/tag\/japanese\/","name":"Japanese","slug":"japanese","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/katiepfeiffer.com\/blog\/wp-json\/wp\/v2\/tags\/647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/katiepfeiffer.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/katiepfeiffer.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/katiepfeiffer.com\/blog\/wp-json\/wp\/v2\/posts?tags=647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}